{"id":142,"count":181,"description":"","link":"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/","name":"Tips","slug":"tips","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tips - Everything Indian<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tips - Everything Indian\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/\" \/>\n<meta property=\"og:site_name\" content=\"Everything Indian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/\",\"url\":\"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/\",\"name\":\"Tips - Everything Indian\",\"isPartOf\":{\"@id\":\"https:\/\/www.everythingindian.com.au\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.everythingindian.com.au\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.everythingindian.com.au\/blog\/#website\",\"url\":\"https:\/\/www.everythingindian.com.au\/blog\/\",\"name\":\"Everything Indian\",\"description\":\"Blogs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.everythingindian.com.au\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tips - Everything Indian","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Tips - Everything Indian","og_url":"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/","og_site_name":"Everything Indian","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/","url":"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/","name":"Tips - Everything Indian","isPartOf":{"@id":"https:\/\/www.everythingindian.com.au\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.everythingindian.com.au\/blog\/category\/tips\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.everythingindian.com.au\/blog\/"},{"@type":"ListItem","position":2,"name":"Tips"}]},{"@type":"WebSite","@id":"https:\/\/www.everythingindian.com.au\/blog\/#website","url":"https:\/\/www.everythingindian.com.au\/blog\/","name":"Everything Indian","description":"Blogs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.everythingindian.com.au\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.everythingindian.com.au\/blog\/wp-json\/wp\/v2\/categories\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.everythingindian.com.au\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.everythingindian.com.au\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.everythingindian.com.au\/blog\/wp-json\/wp\/v2\/posts?categories=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}